{"id":301,"date":"2011-07-06T08:56:30","date_gmt":"2011-07-06T06:56:30","guid":{"rendered":"http:\/\/mapiedra-abogados.es\/wp\/2011\/07\/06\/control-del-dopaje\/"},"modified":"2011-07-06T08:56:30","modified_gmt":"2011-07-06T06:56:30","slug":"control-del-dopaje","status":"publish","type":"post","link":"http:\/\/mapiedra-abogados.es\/wp\/2011\/07\/06\/control-del-dopaje\/","title":{"rendered":"Control del dopaje"},"content":{"rendered":"<p>Se ha publicado en el B.O.E., la Orden PRE\/1832\/2011, de 29 de junio, por la que se regula el \u00e1rea de control del dopaje, el material para la toma de muestras y el protocolo de manipulaci\u00f3n y transporte de muestras de sangre.<\/p>\n<p>Para m\u00e1s informaci\u00f3n, visite la secci\u00f3n normativas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ha publicado en el B.O.E., la Orden PRE\/1832\/2011, de 29 de junio, por la que se regula el \u00e1rea de control del dopaje, el material para la toma de muestras y el protocolo de manipulaci\u00f3n y transporte de muestras de sangre. Para m\u00e1s informaci\u00f3n, visite la secci\u00f3n normativas.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[37],"tags":[],"_links":{"self":[{"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/posts\/301"}],"collection":[{"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/comments?post=301"}],"version-history":[{"count":0,"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/posts\/301\/revisions"}],"wp:attachment":[{"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/media?parent=301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/categories?post=301"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/mapiedra-abogados.es\/wp\/wp-json\/wp\/v2\/tags?post=301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}